{"id":282,"date":"2024-10-17T10:04:00","date_gmt":"2024-10-17T10:04:00","guid":{"rendered":"https:\/\/sista.cnt-ait.info\/?p=282"},"modified":"2026-07-11T10:06:09","modified_gmt":"2026-07-11T10:06:09","slug":"semaine-internationale","status":"publish","type":"post","link":"https:\/\/sista.cnt-ait.info\/index.php\/2024\/10\/17\/semaine-internationale\/","title":{"rendered":"Semaine internationale de lutte contre les salaires impay\u00e9s : un exemple d\u2019action directe au quotidien"},"content":{"rendered":"\n<figure class=\"wp-block-image aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"720\" height=\"471\" src=\"https:\/\/sista.cnt-ait.info\/wp-content\/uploads\/2026\/07\/AIT-Semaine-payement.jpg\" alt=\"\" class=\"wp-image-172\" srcset=\"https:\/\/sista.cnt-ait.info\/wp-content\/uploads\/2026\/07\/AIT-Semaine-payement.jpg 720w, https:\/\/sista.cnt-ait.info\/wp-content\/uploads\/2026\/07\/AIT-Semaine-payement-300x196.jpg 300w\" sizes=\"auto, (max-width: 720px) 100vw, 720px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Chaque ann\u00e9e, les sections de l\u2019AIT (Association Internationale des Travailleurs) organisent en octobre une semaine de lutte contre les salaires impay\u00e9s. En fait, le probl\u00e8me des salaires impay\u00e9s c\u2019est toute l\u2019ann\u00e9e, et c\u2019est bien toute l\u2019ann\u00e9e que nous luttons aux c\u00f4t\u00e9 des travailleurs et des travailleurs pour leur droit le plus basique&nbsp;: que le patron leur donne simplement ce qu\u2019il leur doit. Mais cette semaine permet de mettre en lumi\u00e8re notre action militante au quotidien, que nous menons habituellement sans lui donner de publicit\u00e9.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Si exiger d\u2019\u00eatre pay\u00e9 pour son travail n\u2019a rien de r\u00e9volutionnaire en soi, nous essayons d\u2019utiliser une m\u00e9thode en coh\u00e9rence avec nos conceptions r\u00e9volutionnaires, la m\u00e9thode de l\u2019action directe. Contrairement \u00e0 ce que veut nous faire croire le Pouvoir et les m\u00e9dias, l\u2019action directe cela ne veut pas dire l\u2019action violente. Ce n\u2019est pas non plus l\u2019action spectaculaire pour faire parler de nous dans les journaux ou sur les r\u00e9seaux sociaux. Comme son nom l\u2019indique, l\u2019action directe cela veut dire l\u2019action men\u00e9e directement par les concern\u00e9s \u2013 ici dans ce cas les travailleurs \u2013 sans aucun interm\u00e9diaire, sans aucun repr\u00e9sentant ni porte-parole, qu\u2019il soit politicien (maire, d\u00e9put\u00e9, membre d\u2019un parti politique), ni avocat qui d\u00e9cide \u00e0 la place du plaignant de la strat\u00e9gie de d\u00e9fense, ni m\u00eame repr\u00e9sentant syndical qui parle au nom des travailleurs sans leur avoir demand\u00e9 leur avis au pr\u00e9alable. Cette action directe peut passer par des actes spectaculaires voire violents, mais ce qui caract\u00e9rise l\u2019action directe c\u2019est qu\u2019elle est d\u00e9cid\u00e9e par l\u2019assembl\u00e9e g\u00e9n\u00e9rale des concern\u00e9s et pas seulement par un petit groupe de personne qui prend les d\u00e9cisions pour les autres, lesquels ne sont alors r\u00e9duits qu\u2019au r\u00f4le de simples ex\u00e9cutants. Si on r\u00e9fl\u00e9chit bien, beaucoup de ce qu\u2019on nous pr\u00e9sente comme de l\u2019action directe (que ce soit les blacks blocs ou les manifestations anti bassines) ce n\u2019est pas de l\u2019action directe, mais de l\u2019action spectaculaire \u2026<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">L\u2019action directe bien souvent n\u2019a rien de spectaculaire. Elle commence d\u00e9j\u00e0 par le fait de dire \u00ab&nbsp;non&nbsp;\u00bb, \u00e0 titre individuel, de tenir t\u00eate \u00e0 son chef d\u2019\u00e9quipe, \u00e0 son chef de service, \u00e0 son chef de bureau. A refuser de faire des heures sup\u2019. A exiger d\u2019\u00eatre pay\u00e9 en temps et en heure. Rien de spectaculaire, rien qui ne fera le buzz sur les r\u00e9seaux sociaux. Ce sont des petits gestes du quotidien, des petites victoires qui s\u2019arrachent par petits bouts, et qui permettent de faire monter progressivement la confiance en soi et dans le collectif. Ce n\u2019est pas le r\u00e9formisme (qui vise \u00e0 changer la Loi), car l\u2019action directe n\u2019attend rien de la Loi, laquelle n\u2019est qu\u2019une m\u00e9diation entre les parties concern\u00e9es (les patrons vs les travailleurs) arbitr\u00e9e par l\u2019Etat.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A titre d\u2019exemple de cette m\u00e9thode de l\u2018action directe que nous essayons de pratiquer, nous avons \u00e9t\u00e9 contact\u00e9s la semaine pass\u00e9e par une groupe de travailleuses saisonni\u00e8res \u00e9trang\u00e8res, qui se posaient des questions sur la l\u00e9galit\u00e9 de leur conditions de travail (logement et conditions de vie, non payement des primes), et se demandaient si elles avaient le droit d\u2019exiger quelque chose. D\u00e8s r\u00e9ception de leur demande, nous leur avons propos\u00e9 de les rencontrer pour discuter de ce qu\u2019il \u00e9tait possible de faire collectivement. Nous avons proc\u00e9d\u00e9 \u00e0 une analyse juridique de leurs demandes, en nous appuyant sur le r\u00e9seau de compagnons qui ont une exp\u00e9rience solide de ces questions, soit parce qu\u2019ils sont militants, soit de par leur activit\u00e9 professionnelle (inspection du travail). Il est apparu qu\u2019en fait, la plupart des points soulev\u00e9s par les saisonni\u00e8res n\u2019\u00e9taient pas \u00abill\u00e9gaux&nbsp;\u00bb. Le patron les exploitait mais le plus l\u00e9galement du monde&nbsp;! C\u2019\u00e9tait moralement inique mais compl\u00e8tement conforme au sacro-saint Code du Travail. Apr\u00e8s avoir expliqu\u00e9 cela aux travailleuses, nous leur avons aussi dit que rien n\u2019interdisait non plus de demander plus que ce qui est pr\u00e9vu par le Code du Travail. Et que pour se donner le maximum de chance de gagner, il \u00e9tait pr\u00e9f\u00e9rable d\u2019agir collectivement, de mani\u00e8re group\u00e9e et sans d\u00e9signer au patron un interlocuteur en particulier, pour \u00e9viter de lui d\u00e9signer une cible sur qui faire peser la r\u00e9pression. Les saisonni\u00e8res ont d\u00e9j\u00e0 mis en application cette m\u00e9thode de l\u2019action directe, et d\u00e9j\u00e0 cela leur a permis d\u2019obtenir la mise \u00e0 disposition d\u2019une machine \u00e0 laver pour leur linge. C\u2019est une fa\u00e7on de r\u00e9cup\u00e9rer du salaire, car il n\u2019y a plus besoin de payer \u00e0 la laverie pour laver son linge. Cela peut para\u00eetre d\u00e9risoire, mais pourvoir mettre des v\u00eatements propres quand vous travaillez dans les champs, c\u2019est une question de dignit\u00e9. Or les r\u00e9volutions se font souvent \u2013 si ce n\u2019est toujours \u2013 pour des raisons de dignit\u00e9, bien plus que pour toute autre raison strictement mat\u00e9rielle.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En concluant voici le mot que nous a envoy\u00e9 la compagne qui nous avait contact\u00e9 au nom du groupe&nbsp;:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00ab&nbsp;<em>je voudrai vous transmettre mes remerciements car vous m\u2019avez rappel\u00e9 que c\u2019est justice le fait que je demande certaines choses aux Patrones en \u00e9change de ma force&nbsp; du travail, m\u00eame si le loi ne l\u2019impose pas. J\u2019ai toujours des probl\u00e8mes avec les patrons, et parfois aussi avec mes coll\u00e8gues qui me disent que je suis \u00ab&nbsp;trop exigeante&nbsp;\u00bb (alors qu\u2019on a des conditions super super pr\u00e9caires \u00e0 mon avis) et \u00e7a me fait,&nbsp;parfois, baisser mon niveau du exigence.<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Si je reviens travailler dans la r\u00e9gion, bien s\u00fbr que je vous contacterai pour vous rejoindre et coop\u00e9rer avec vous.&nbsp;<\/em>\u00bb<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La lutte continue \u2026<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><em>Des militantes et militants de la CNT-AIT<\/em><\/strong><\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<p class=\"wp-block-paragraph\">SISTA CNT-AIT, Section Internationaliste Syndicale des Travailleurs Agricoles de la CNT-AIT (Association Internationale des Travailleurs)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">L&rsquo;union fait la force ! Travailleurs agricoles, unissions nous !<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00a1La uni\u00f3n hace la fuerza! \u00a1Trabajadores agr\u00edcolas, un\u00e1monos!<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u0627\u0644\u0648\u062d\u062f\u0629 \u0642\u0648\u0629! \u064a\u0627 \u0639\u0645\u0627\u0644 \u0627\u0644\u0645\u0632\u0627\u0631\u0639\u060c \u0641\u0644\u0646\u062a\u062d\u062f!<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u0415\u0434\u0438\u043d\u0441\u0442\u0432\u043e \u2013 \u0441\u0438\u043b\u0430! \u0421\u0435\u043b\u044c\u0441\u043a\u043e\u0445\u043e\u0437\u044f\u0439\u0441\u0442\u0432\u0435\u043d\u043d\u044b\u0435 \u0440\u0430\u0431\u043e\u0447\u0438\u0435, \u0441\u043e\u0435\u0434\u0438\u043d\u044f\u0439\u0442\u0435\u0441\u044c!<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Unitatea face puterea! Lucr\u0103tori agricoli, haide\u021bi s\u0103 ne unim!<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Unity is strength! Farm workers, let&rsquo;s unite!<\/p>\n\n\n\n<p class=\"has-bright-red-color has-text-color has-link-color wp-elements-fd94e014e70cf56c978df46b0f3c7050 wp-block-paragraph\">contact@cnt-ait.info<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Chaque ann\u00e9e, les sections de l\u2019AIT (Association Internationale des Travailleurs) organisent en octobre une semaine de lutte contre les salaires impay\u00e9s. En fait, le probl\u00e8me des salaires impay\u00e9s c\u2019est toute l\u2019ann\u00e9e, et c\u2019est bien toute l\u2019ann\u00e9e que nous luttons aux c\u00f4t\u00e9 des travailleurs et des travailleurs pour leur droit le plus basique&nbsp;: que le patron [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":172,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-container-style":"default","site-container-layout":"default","site-sidebar-layout":"default","disable-article-header":"default","disable-site-header":"default","disable-site-footer":"default","disable-content-area-spacing":"default","footnotes":""},"categories":[15],"tags":[],"class_list":["post-282","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-luttes-actu"],"_links":{"self":[{"href":"https:\/\/sista.cnt-ait.info\/index.php\/wp-json\/wp\/v2\/posts\/282","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sista.cnt-ait.info\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sista.cnt-ait.info\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sista.cnt-ait.info\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/sista.cnt-ait.info\/index.php\/wp-json\/wp\/v2\/comments?post=282"}],"version-history":[{"count":1,"href":"https:\/\/sista.cnt-ait.info\/index.php\/wp-json\/wp\/v2\/posts\/282\/revisions"}],"predecessor-version":[{"id":283,"href":"https:\/\/sista.cnt-ait.info\/index.php\/wp-json\/wp\/v2\/posts\/282\/revisions\/283"}],"wp:attachment":[{"href":"https:\/\/sista.cnt-ait.info\/index.php\/wp-json\/wp\/v2\/media?parent=282"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sista.cnt-ait.info\/index.php\/wp-json\/wp\/v2\/categories?post=282"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sista.cnt-ait.info\/index.php\/wp-json\/wp\/v2\/tags?post=282"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}