{"id":236,"date":"2006-01-24T08:47:00","date_gmt":"2006-01-24T08:47:00","guid":{"rendered":"https:\/\/sista.cnt-ait.info\/?p=236"},"modified":"2026-07-11T10:02:30","modified_gmt":"2026-07-11T10:02:30","slug":"mas-riols","status":"publish","type":"post","link":"https:\/\/sista.cnt-ait.info\/index.php\/2006\/01\/24\/mas-riols\/","title":{"rendered":"QUELQUES QUESTIONS AUTOUR DE LA GREVE DES SAISONNIERS AGRICOLES DU MAS RIOLS (P.O)"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Premi\u00e8re publication : mardi 24 janvier 2006<br><br><strong>Les Pyr\u00e9nn\u00e9es orientales sont un d\u00e9partement largement rural avec de nombreuses productions saisonni\u00e8res (vendanges, cueillettes, etc \u2026). La pr\u00e9carit\u00e9 est une tradition quasi \u00ab\u00a0culturelle\u00a0\u00bb de ces activit\u00e9s, o\u00f9 la main d\u2019oeuvre s\u2019ach\u00e8te \u00e0 vil prix et de pr\u00e9f\u00e9rence quand elle est immigr\u00e9e sans papiers, c\u2019est \u00e0 dire \u00e0 l\u2019enti\u00e8re merci d\u2019un patron f\u00e9odal. Mais il arrive que les esclaves en aient marre et se rebiffe. C\u2019est ce e qui s\u2019est pass\u00e9 au Mas Riols. Des compagnons, habitant du village, se sont solidaris\u00e9 avec la lutte spontan\u00e9e, qui en m\u00eame temps qu\u2019elle commen\u00e7ait \u00e0 se structurer elle m\u00eame \u00e0 vu arriver les \u00ab\u00a0gestionnaires-pompiers\u00a0\u00bb de la CGT, et leur sabotage de l\u2019auto-organisation. R\u00e9cit d\u2019une reprise en main syndicale <\/strong><\/p>\n\n\n\n<h3 class=\"wp-block-heading\">CHRONOLOGIE<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Mercredi 23\/11&nbsp;:<\/strong> premi\u00e8re rencontre avec les gr\u00e9vistes du mas Riols \u00e0 Latour Bas Elne (66). Il s\u2019agit d\u2019une grosse propri\u00e9t\u00e9 agricole de maraichage de 130 hectares. Le patron dispose \u00e9galement d\u2019autres propri\u00e9t\u00e9s en Ile de France. En tant qu\u2019habitant d\u2019Elne j\u2019apporte mon soutien. Il s\u2019agit de 17 ouvriers agricoles portugais, de 6 roumains et d\u2019un marocain, qui r\u00e9clament plusieurs mois impay\u00e9s. Certains sont log\u00e9s sur place, dans des conditions mis\u00e9rables. Tous occupent la ferme en campant et en bloquant un camion. La discussion s\u2019engage. Ils ont attaqu\u00e9 le patron aux Prud\u2019hommes. Ils expliquent qu\u2019ils ont fait venir la Direction du Travail \u2026 qui est venue avec la PAF&nbsp;[<a href=\"http:\/\/sipncntait.free.fr\/article_1448.html#nb1\">1<\/a>]. Moralit\u00e9 t\u00e9l\u00e9vis\u00e9e (d\u00e9j\u00e0 la t\u00e9l\u00e9vision&nbsp;!)&nbsp;: les roumains se retrouvent au centre de r\u00e9tention de Rivesaltes et expuls\u00e9s. Deux jours apr\u00e8s, l\u2019un d\u2019eux appelle de Roumanie\u2026<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Jeudi 24\/11&nbsp;:<\/strong> je vais v\u00e9rifier \u00e0 la Chambre d\u2019Agriculture puis \u00e0 la MSA&nbsp;[<a href=\"http:\/\/sipncntait.free.fr\/article_1448.html#nb2\">2<\/a>] le n\u00b0&nbsp;de siret&nbsp;[<a href=\"http:\/\/sipncntait.free.fr\/article_1448.html#nb3\">3<\/a>] de l\u2019employeur. Le num\u00e9ro ne correspond pas \u00e0 celui des bulletins de salaires&nbsp;! Normal m\u2019est-il expliqu\u00e9&nbsp;: c\u2019est un groupement d\u2019entrepreneurs qui poss\u00e8de plusieurs domaines dans les P.O&nbsp;[<a href=\"http:\/\/sipncntait.free.fr\/article_1448.html#nb4\">4<\/a>] et en Ile de France. Affolement des ouvriers. Je propose de prendre le camion de la ferme et d\u2019aller vendre directement les produits sur les march\u00e9s. R\u00e9ticence des gr\u00e9vistes d\u00e9j\u00e0 culpabilis\u00e9s par le fait de faire gr\u00e8ve. Proposition de faire des banderoles. Apr\u00e8s h\u00e9sitation, ils acceptent.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Une voiture de la mairie s\u2019arr\u00eate\u00a0: c\u2019est le secr\u00e9taire de mairie, il est du Parti Communiste (PC)\u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00a0\u00a0\u00a0&#8211; \u00a0\u00a0\u00ab Vous n\u2019avez besoin de rien\u00a0?\u00a0\u00bb<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00a0&#8211; \u00ab Du bois pour du feu \u00ab\u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00a0\u00a0&#8211; \u00ab\u00a0Et vous Monsieur vous n\u2019avez pas d\u2019accent\u00a0!\u00a0\u00bb<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00a0\u00a0&#8211; \u00ab\u00a0H\u00e9 non, je l\u2019ai perdu depuis longtemps. Pourquoi, il en faut un\u00a0?\u00a0\u00bb<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">J\u2019avertis des copains, nous revenons et expliquons qu\u2019il leur appartient d\u2019\u00e9crire ce qu\u2019ils veulent, que durant leur lutte ils ne doivent avoir confiance qu\u2019en eux et ne pas faire confiance aux autres, ni m\u00eame \u00e0 nous. Ils confectionnent leur banderole \u00ab&nbsp;<strong> OUVRIERS DU MAS RIOLS EN GREVE. <\/strong>&nbsp;\u00bb et l\u2019accrochent \u00e0 l\u2019entr\u00e9e de la ferme le long de la route, bien visible.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Vendredi 25\/11&nbsp;:<\/strong> la banderole est toujours l\u00e0, le feu br\u00fble, le bois municipal ne manque pas, la gr\u00e8ve continue. Une voiture s\u2019arr\u00eate&nbsp;: \u00ab&nbsp;<em>Bonjour je suis de la CGT, je viens de Montpellier pour m\u2019occuper de vous<\/em>\u00ab&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La t\u00e9l\u00e9 arrive quelques minutes plus tard. Le permanent CGT s\u2019assied \u00e0 l\u2019unique table en plein air et fait semblant d\u2019\u00e9crire. Les portugais sont sollicit\u00e9s par la t\u00e9l\u00e9 mais ne sont pas habitu\u00e9s \u00e0 ces mises en sc\u00e8ne et de plus ont des difficult\u00e9s \u00e0 s\u2019exprimer en fran\u00e7ais&nbsp;:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00ab&nbsp;<em> Il me doit quatre mois de salaire mais les roumains ont travaill\u00e9 et ils ont \u00e9t\u00e9 embarqu\u00e9s sans \u00eatre pay\u00e9s, et il y a l\u2019arabe qui habite sur un autre mas, \u00e0 lui il lui doit 11 mois<\/em>&nbsp;\u00bb,<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00ab&nbsp;<em> putain c\u2019est pas normal, les esclaves on les nourrissait, nous&nbsp;: Rien&nbsp;!<\/em>&nbsp;\u00bb<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00ab&nbsp;<em> A moi il me doit deux mois, hier le patron est sorti et m\u2019a mis un ch\u00e8que dans la poche, je lui ai jet\u00e9, il nous paye tous ou personne.<\/em>&nbsp;\u00bb<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La seule chose qui passe \u00e0 la t\u00e9l\u00e9, c\u2019est la CGT faisant semblant de prendre tout en main. Et la banderole, o\u00f9 ils rajoutent leur sigle. Les portugais font la gueule. Ils d\u00e9cident de faire une autre banderole&nbsp;: \u00ab&nbsp;<strong> EN GREVE DEPUIS LE 18.11 3-4-5 MOIS SANS PAYE. CONGES ET HEURES SUPPLEMENTAIRE NON PAYES. <\/strong>&nbsp;\u00bb<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le permanent CGT de Montpellier est venu accompagn\u00e9 d\u2019un administrateur de la MSA. Premi\u00e8re tentative CGT&nbsp;: \u00e0 propos du marocain (11 mois de salaires et une retraite \u00e9nigmatique, en maladie apr\u00e8s une crise cardiaque dans un sillon de salade, transport\u00e9 et op\u00e9r\u00e9 \u00e0 l\u2019h\u00f4pital)&nbsp;: \u00ab&nbsp;<em> Celui-l\u00e0 on va le n\u00e9gocier \u00e0 part <\/em>&nbsp;\u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Je gueule aux portugais&nbsp;: \u00ab&nbsp;<em>Il n\u2019y a rien \u00e0 n\u00e9gocier, il faut faire les totaux pour chacun avec les heures sup. ils payent tout et tout le monde. C\u2019est ce que vous avez d\u00e9cid\u00e9 non&nbsp;?<\/em>\u00ab&nbsp;. C\u2019est s\u00fbr, on bouge pas d\u2019ici.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La CGT comprend qu\u2019elle ne va pas conclure l\u2019affaire en coup de brosse&nbsp;: \u00ab&nbsp;<em> Bon, on va n\u00e9gocier les retards de salaires, vous lib\u00e9rez les v\u00e9hicules et pour les heures suppl\u00e9mentaires on verra plus tard.<\/em>&nbsp;\u00bb<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Les gr\u00e9vistes&nbsp;: \u00ab&nbsp;<em> C\u2019est pas normal, on veut tout, on ne bouge rien, le camion ne bouge pas, les tracteurs ne bougent pas. <\/em>&nbsp;\u00bb<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nous prenons la parole pour dire que les patrons doivent payer les jours de gr\u00e8ve. Il y a eu gr\u00e8ve non pour des revendications salariales mais pour des salaires impay\u00e9s. Il faut bouffer, payer un loyer etc etc. S\u2019ils ont fait gr\u00e8ve c\u2019est la faute des patrons. Discussion vive, ils ne sont pas tr\u00e8s chauds (c\u2019est pas normal d\u2019\u00eatre pay\u00e9s sans travailler&nbsp;!). D\u00e9cision tout de m\u00eame&nbsp;: \u00ab&nbsp;<em>On veut qu\u2019il paye les jours de gr\u00e8ve&nbsp;! <\/em>&nbsp;\u00bb<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">N\u00e9gociations CGT -employeur-ouvriers. Ils vont percevoir les salaires et avoir les fiches de paye. Rien pour la gr\u00e8ve. Rien pour le marocain. Nous partons dans son taudis pour l\u2019aider \u00e0 trier ses papiers (Il est log\u00e9 par l\u2019employeur dans une pi\u00e8ce insalubre d\u2019un mas voisin, sans eau, sans chauffage, table de camping, r\u00e9chaud. Le mas appartient \u00e0 l\u2019h\u00f4pital de Perpignan&nbsp;!). Nous mettons les papiers sous le nez de la CGT&nbsp;! Il est \u00e0 la retraite&nbsp;! Il croyait qu\u2019il \u00e9tait en maladie, il a des bulletins de salaires 2004 mais maintient n\u2019avoir pas \u00e9t\u00e9 pay\u00e9&nbsp;! Les portugais confirment.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">18 heures, une voiture, quatre mecs descendent dans la nuit avec leurs badges fluo&nbsp;: \u00ab&nbsp;<em> Bonjour Messieurs nous sommes la CGT de la mairie d\u2019Elne, nous venons vous soutenir&nbsp;!<\/em>&nbsp;\u00bb&nbsp;\u00bb (apr\u00e8s 8 jours de gr\u00e8ve) La bande des 4 c\u00e9g\u00e9tistes d\u2019Elne fait semblant de s\u2019int\u00e9resser \u00e0 la gr\u00e8ve, propose un soutien de la mairie et demande au Montpelli\u00e9rain&nbsp;: \u00ab&nbsp;<em>Et vous Monsieur, qui \u00eates-vous&nbsp;?<\/em>&nbsp;\u00bb R\u00e9ponse de l\u2019int\u00e9ress\u00e9&nbsp;: \u00ab&nbsp;<em>Je suis de la CGT agricole de Montpellier. <\/em>&nbsp;\u00bb Malaise des CGTistes&nbsp;! \u2026<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Des ouvriers portugais viennent de temps en temps soutenir, ils ont tous travaill\u00e9 ici, en sont partis \u00e9c\u0153ur\u00e9s. Le marocain nous explique&nbsp;: eux aussi ils ont \u00e9t\u00e9 \u00ab&nbsp;baptis\u00e9s&nbsp;\u00bb \u2026 Aucun autre soutien agricole voisin. Le soutien viendra le lendemain non sous la forme de la CGT municipale sinon de celle du Secours Populaire \u00ab&nbsp;<em>envoy\u00e9 par la mairie<\/em>&nbsp;\u00bb&nbsp;: caf\u00e9, huile, sucre, riz au lait \u00e0 volont\u00e9, p\u00e2tes, et du couscous&nbsp;! Le C\u00e9g\u00e9tiste de la MSA a embarqu\u00e9 le marocain pour photographier son taudis.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Week-end calme, nous passons tous les jours, apr\u00e8s \u00e7a s\u2019acc\u00e9l\u00e8re<\/strong>. Un copain a \u00e9t\u00e9 reconnu par la CGT comme \u00e9tant de la CNT-AIT (m\u00eame si nous ne l\u2019avons jamais affich\u00e9). Le montpelli\u00e9rain de la CGT et l\u2019administrateur MSA ont mis leurs badges qu\u2019ils n\u2019avaient pas port\u00e9 jusque l\u00e0&nbsp;!\u2026 L\u2019argent a \u00e9t\u00e9 vir\u00e9, fiches de paye \u00e9tablies, rien pour le marocain. Le CGT-MSA dit que le marocain a des retards de versement maladie qui lui seront vers\u00e9s par la MSA et que l\u2019employeur ne verse pas beaucoup de cotisations\u2026 Mais \u00e7a gueule de nouveau, \u00e0 l\u2019un il manque 1000\u20ac, \u00e0 l\u2019autre 2000\u20ac. Ren\u00e9gociations CGT-ouvriers-employeur&nbsp;: les heures suppl\u00e9mentaires sont pay\u00e9es sous forme de primes de panier et de trajets (certains habitent sur place \u2026). Nous faisons valoir que les heures suppl\u00e9mentaires qui ne figurent pas sur les bulletins sont autant de moins de d\u00e9clar\u00e9 \u00e0 la MSA et donc comptabilis\u00e9es en moins pour leurs maladie-retraite. La CGT leur dit&nbsp;: \u00ab&nbsp;<em>\u00e7a on verra plus tard&nbsp;!\u2026 <\/em>&nbsp;\u00bb La t\u00e9l\u00e9 cabl\u00e9e arrive, demande aux portugais&nbsp;: \u00ab&nbsp;<em> faites-nous une d\u00e9claration <\/em>&nbsp;\u00bb<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La r\u00e9ponse des portugais ne se fait pas attendre&nbsp;: \u00ab&nbsp;<em> putain, on parle on parle et il ne passe rien \u00e0 la t\u00e9l\u00e9&nbsp;! Qu\u2019est-ce que \u00e7a veut dire&nbsp;?<\/em>&nbsp;\u00bb.Le c\u00e2ble repart.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">NEGOCIATIONS \u2026<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Les discussions ouvriers-CGT se tenaient en notre pr\u00e9sence, le lieu s\u2019\u00e9loigne petit \u00e0 petit durant la journ\u00e9e jusqu\u2019\u00e0 se tenir dans une pi\u00e8ce (sous pr\u00e9texte qu\u2019il fait du vent). La CGT commence \u00e0 nous exclure. Une ouvri\u00e8re portugaise s\u2019arr\u00eate pour engueuler les 2 autres, et son mari&nbsp;: elle est partie du mas, elle a assign\u00e9 l\u2019employeur au tribunal, son mari ne lui avait pas dit qu\u2019ils \u00e9taient en gr\u00e8ve depuis plus de dix jours&nbsp;! Elle gueule&nbsp;: \u00ab&nbsp;<em> Qui a dit au syndicat de venir&nbsp;? On ne veut pas de syndicat&nbsp;! Il n\u2019y a rien \u00e0 n\u00e9gocier&nbsp;! <\/em>&nbsp;\u00bb Malaise.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le marocain reste avec nous et ne veut pas aller au bureau, nous le poussons presque&nbsp;! La gendarmerie vient faire un tour pour \u00ab&nbsp;<em>voir s\u2019il y a des roumains <\/em>&nbsp;\u00bb. Acc\u00e9l\u00e9ration d\u2019allers-retours incessants chez l\u2019employeur qui se tient depuis une semaine et toute la journ\u00e9e a la disposition du d\u00e9l\u00e9gu\u00e9 CGT. Les c\u00e9g\u00e9tistes ne nous adressent plus la parole. Fin de soir\u00e9e&nbsp;: un ouvrier nous apprend que la CGT a n\u00e9goci\u00e9&nbsp;: \u00ab&nbsp;<em>vous avez re\u00e7u \u00e7a, vous reprenez le travail&nbsp;! <\/em>&nbsp;\u00bb Nous voulons participer \u00e0 la discussion&nbsp;: refus de la CGT qui tente de fermer la porte de force. Je demande aux gr\u00e9vistes s\u2019ils sont d\u2019accord avec \u00e7a&nbsp;: pas de r\u00e9ponse. Le c\u00e9g\u00e9tiste gueule&nbsp;: \u00ab&nbsp;<em>c\u2019est moi qui d\u00e9cide&nbsp;!<\/em>&nbsp;\u00bb<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">On s\u2019en va, ils ont mon t\u00e9l\u00e9phone. Le lendemain nous y retournons \u00e0 deux pour r\u00e9cup\u00e9rer des outils, ils sont g\u00ean\u00e9s de leur attitude, disent qu\u2019ils se sont aper\u00e7us du comportement CGT qui tendait \u00e0 nous isoler mais ne sont pas plus enthousiastes que \u00e7a pour nous voir revenir. Ils disent vouloir continuer la gr\u00e8ve jusqu\u2019\u00e0 ce que tout soit r\u00e9gl\u00e9. Pour le marocain rien n\u2019est r\u00e9gl\u00e9. La mairie d\u2019Elne et la MSA disent au ils vont s\u2019occuper de lui trouver un appartement.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">EPILOGUE<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Deux copains retrouvent les ouvriers au Tribunal&nbsp;!. Le montpelli\u00e9rain CGT est toujours l\u00e0&nbsp;! Et la t\u00e9l\u00e9&nbsp;! Et la radio&nbsp;! Ils sont venus assister au proc\u00e8s de l\u2019employeur pour l\u2019emploi des roumains (pour ces derniers, bien entendu, aucune n\u00e9gociation de salaires clandestins, soit un gain patronal de plus de 10 mois de travail). Le c\u00e9g\u00e9tiste discute avec l\u2019avocat des portugais, ils ne paraissent pas d\u2019accord. Aucune information ne filtre, les portugais sont distants. Dans le hall du tribunal, le d\u00e9l\u00e9gu\u00e9 r\u00e9gional CGT leur donne RV au local de la CGT d\u2019Elne pour qu\u2019ils prennent leurs cartes&nbsp;: \u00e0 tarif r\u00e9duit compte tenu de la gr\u00e8ve et de la proximit\u00e9 de No\u00ebl&nbsp;! \u2026<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A ce jour d\u00e9but janvier, apr\u00e8s avoir rencontr\u00e9 des gr\u00e9vistes du Mas Riols il s\u2019av\u00e8re\u00a0<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>que tous les gr\u00e9vistes ne travaillent plus au Mas.<\/li>\n\n\n\n<li>qu\u2019ils n\u2019ont encaiss\u00e9 que le minimum qui a \u00e9t\u00e9 n\u00e9goci\u00e9, c\u2019est-a-dire <\/li>\n\n\n\n<li>que les heures suppl\u00e9mentaires n\u2019ont pas \u00e9t\u00e9 pay\u00e9es.<\/li>\n\n\n\n<li>que les cong\u00e9s pay\u00e9s n\u2019ont pas \u00e9t\u00e9 r\u00e9gl\u00e9s.<\/li>\n\n\n\n<li>que l\u2019exploitation refonctionne avec de nouveaux travailleurs, mais maghr\u00e9bins cette fois (c est une fa\u00e7on de s assurer que la transmission de l historique de la lutte sera plus difficile, ne serait ce que pour des raisons linguistiques \u2026 diviser pour mieux r\u00e9gner \u2026 NDLR).<\/li>\n\n\n\n<li>que le vieux Marocain n\u2019a rien touch\u00e9 et vit toujours dans des conditions d\u00e9plorables dans son taudis malges les promesses de relogement \u2026<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\">INTERROGATIONS MINIMALES<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">A la suite de cette exp\u00e9rience, il nous a sembl\u00e9 important d\u2019\u00e9tablir une liste des questions minimales que devrait se poser tout militant sinc\u00e8re&nbsp;:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Qui a envoy\u00e9 la CGT\u00a0?<\/li>\n\n\n\n<li>Pourquoi la CGT de Montpellier et pas celle de Perpignan\u00a0?<\/li>\n\n\n\n<li>Pourquoi l\u2019UR CGT a-t-elle mobilis\u00e9 un d\u00e9l\u00e9gu\u00e9 durant plus d\u2019une semaine pr\u00e8s de 12 heures par jour alors qu\u2019aucun des ouvriers n\u2019\u00e9tait syndiqu\u00e9 \u00e0 la CGT\u00a0?<\/li>\n\n\n\n<li>Pourquoi l\u2019employeur a-t-il n\u00e9goci\u00e9 avec la CGT\u00a0?<\/li>\n\n\n\n<li>Pourquoi l\u2019UD CGT ne s\u2019est-elle pas manifest\u00e9e\u00a0?<\/li>\n\n\n\n<li>Quelles sont la r\u00e9alit\u00e9 et l\u2019actualit\u00e9 des cotisations patronales du G.E aupr\u00e8s de la M.S.A\u00a0?<\/li>\n\n\n\n<li>Comment et pourquoi le G.E dispose-t-il d\u2019une immense propri\u00e9t\u00e9 appartenant \u00e0 l\u2019h\u00f4pital et, qui plus est, y loge un ouvrier dans des conditions ignobles\u00a0?<\/li>\n\n\n\n<li>Comment et pourquoi 4 syndiqu\u00e9s CGT, employ\u00e9s de la mairie d\u2019Elne, venus \u00ab\u00a0soutenir\u00a0\u00bb ne savaient pas que la CGT de Montpellier \u00e9tait d\u00e9j\u00e0 sur place\u00a0?<\/li>\n\n\n\n<li>Comment le Groupement d\u2019employeur (GE) a-t-il fait venir des ouvriers roumains clandestins\u00a0?<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Cette lutte aurait pu \u00eatre le d\u00e9but de quelque chose d\u2019exemplaire pour la r\u00e9gion \u2026 Mais il ne fallait pas que le lait d\u00e9borde de la casserole \u2026<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">CNT AIT PERPIGNAN<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"mailto:perpignan@cnt-ait.info\">perpignan@cnt-ait.info<\/a><\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<p class=\"wp-block-paragraph\">[<a href=\"http:\/\/sipncntait.free.fr\/article_1448.html#nh1\">1<\/a>] Police de l\u2019Air et des Fronti\u00e8res, qui traque les sans papiers<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">[<a href=\"http:\/\/sipncntait.free.fr\/article_1448.html#nh2\">2<\/a>] Mutualit\u00e9 Sociale Agricole&nbsp;: la caisse de s\u00e9cu sp\u00e9cifique des professions agricoles<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">[<a href=\"http:\/\/sipncntait.free.fr\/article_1448.html#nh3\">3<\/a>] num\u00e9ro de registre unique sp\u00e9cifique \u00e0 l\u2019employeur<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">[<a href=\"http:\/\/sipncntait.free.fr\/article_1448.html#nh4\">4<\/a>] Pyr\u00e9n\u00e9es Orientales , 66<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<p class=\"wp-block-paragraph\">SISTA CNT-AIT, Section Internationaliste Syndicale des Travailleurs Agricoles de la CNT-AIT (Association Internationale des Travailleurs)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">L&rsquo;union fait la force ! Travailleurs agricoles, unissions nous !<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00a1La uni\u00f3n hace la fuerza! \u00a1Trabajadores agr\u00edcolas, un\u00e1monos!<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u0627\u0644\u0648\u062d\u062f\u0629 \u0642\u0648\u0629! \u064a\u0627 \u0639\u0645\u0627\u0644 \u0627\u0644\u0645\u0632\u0627\u0631\u0639\u060c \u0641\u0644\u0646\u062a\u062d\u062f!<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u0415\u0434\u0438\u043d\u0441\u0442\u0432\u043e \u2013 \u0441\u0438\u043b\u0430! \u0421\u0435\u043b\u044c\u0441\u043a\u043e\u0445\u043e\u0437\u044f\u0439\u0441\u0442\u0432\u0435\u043d\u043d\u044b\u0435 \u0440\u0430\u0431\u043e\u0447\u0438\u0435, \u0441\u043e\u0435\u0434\u0438\u043d\u044f\u0439\u0442\u0435\u0441\u044c!<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Unitatea face puterea! Lucr\u0103tori agricoli, haide\u021bi s\u0103 ne unim!<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Unity is strength! Farm workers, let&rsquo;s unite!<\/p>\n\n\n\n<p class=\"has-bright-red-color has-text-color has-link-color wp-elements-fd94e014e70cf56c978df46b0f3c7050 wp-block-paragraph\">contact@cnt-ait.info<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Premi\u00e8re publication : mardi 24 janvier 2006 Les Pyr\u00e9nn\u00e9es orientales sont un d\u00e9partement largement rural avec de nombreuses productions saisonni\u00e8res (vendanges, cueillettes, etc \u2026). La pr\u00e9carit\u00e9 est une tradition quasi \u00ab\u00a0culturelle\u00a0\u00bb de ces activit\u00e9s, o\u00f9 la main d\u2019oeuvre s\u2019ach\u00e8te \u00e0 vil prix et de pr\u00e9f\u00e9rence quand elle est immigr\u00e9e sans papiers, c\u2019est \u00e0 dire \u00e0 [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":267,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-container-style":"default","site-container-layout":"default","site-sidebar-layout":"default","disable-article-header":"default","disable-site-header":"default","disable-site-footer":"default","disable-content-area-spacing":"default","footnotes":""},"categories":[15],"tags":[],"class_list":["post-236","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-luttes-actu"],"_links":{"self":[{"href":"https:\/\/sista.cnt-ait.info\/index.php\/wp-json\/wp\/v2\/posts\/236","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sista.cnt-ait.info\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sista.cnt-ait.info\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sista.cnt-ait.info\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/sista.cnt-ait.info\/index.php\/wp-json\/wp\/v2\/comments?post=236"}],"version-history":[{"count":1,"href":"https:\/\/sista.cnt-ait.info\/index.php\/wp-json\/wp\/v2\/posts\/236\/revisions"}],"predecessor-version":[{"id":279,"href":"https:\/\/sista.cnt-ait.info\/index.php\/wp-json\/wp\/v2\/posts\/236\/revisions\/279"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sista.cnt-ait.info\/index.php\/wp-json\/wp\/v2\/media\/267"}],"wp:attachment":[{"href":"https:\/\/sista.cnt-ait.info\/index.php\/wp-json\/wp\/v2\/media?parent=236"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sista.cnt-ait.info\/index.php\/wp-json\/wp\/v2\/categories?post=236"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sista.cnt-ait.info\/index.php\/wp-json\/wp\/v2\/tags?post=236"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}